{"id":3711,"date":"2026-03-02T21:32:21","date_gmt":"2026-03-02T21:32:21","guid":{"rendered":"https:\/\/slipstream-it.local\/resources\/slipstream-co-autrice-del-primo-studio-completo-sui-costi-della-teleangiectasia-emorragica-ereditaria-nellamerican-journal-of-hematology\/"},"modified":"2026-06-19T01:31:23","modified_gmt":"2026-06-19T01:31:23","slug":"slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology","status":"publish","type":"resource","link":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/","title":{"rendered":"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell&#8217;American Journal of Hematology"},"content":{"rendered":"<section id=\"hero-6a581da6ddaee\"\n         class=\"centered-hero d-flex align-items-center text-center centered-hero--no-cards\"\n         style=\"background-color:#0f2060;--hero-video-overlay:rgba(0,0,0,0.35)\">\n\n    \n    \n    \n    <div class=\"container py-5 hero-content\">\n        <div class=\"row justify-content-center\">\n            <div class=\"col-xl-12\">\n\n                \n                                            <p class=\"mb-3 kicker\" style=\"\">\n                            Comunicato stampa                        <\/p>\n                    \n                                            <h1 class=\"fw-bold display-3 mb-3 title\" style=\"margin-left:auto;margin-right:auto\">\n                            Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell&#039;American Journal of Hematology                        <\/h1>\n                    \n                    \n                    \n                    \n                \n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<div class=\"wp-block-columns are-vertically-aligned-center column-lines-bg is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Blue Bell, PA \u2013 10 luglio 2025<\/strong> \u2013 Slipstream, partner tecnologico di fiducia al servizio dell&#8217;industria farmaceutica e biofarmaceutica, \u00e8 orgogliosa di annunciare la sua co-autoria di uno studio rivoluzionario sulla teleangiectasia emorragica ereditaria (HHT), recentemente pubblicato sull&#8217;<em>American Journal of Hematology<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo studio, <em>\u201cCharacterizing the Healthcare Utilization and Costs of Hereditary Hemorrhagic Telangiectasia\u201d<\/em>, \u00e8 il pi\u00f9 grande studio mai condotto su pazienti affetti da HHT, includendo oltre 24.000 pazienti che convivono con questa rara malattia emorragica ereditaria. La ricerca rivela che, all&#8217;interno di questo campione, i costi medici diretti per l&#8217;HHT hanno superato i 450 milioni di dollari all&#8217;anno negli Stati Uniti, trainati principalmente dal trattamento delle complicazioni legate al sanguinamento, inclusa l&#8217;anemia. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c<\/strong>Sfruttando la Healthcare Map<sup>\u00ae<\/sup> di Komodo Health, che include i dati di oltre 330 milioni di pazienti negli Stati Uniti, siamo stati in grado di caratterizzare una malattia rara la cui storia naturale e il cui peso non sono mai stati ben definiti o pienamente compresi<strong>\u201d<\/strong>, ha dichiarato <strong><strong>Tracy J. Mayne, PhD<\/strong><\/strong>, Senior Vice President of Regulatory and Life Science Research presso Slipstream. <strong>\u201c<\/strong>Ora sappiamo che quasi il 60% dei pazienti con diagnosi di HHT presenta emorragie cos\u00ec gravi da causare anemia, e una parte significativa di questi pazienti riceve frequenti infusioni di ferro EV e\/o trasfusioni di globuli rossi. Il peso sia per i pazienti che per il sistema sanitario \u00e8 enorme, con implicazioni significative per l&#8217;advocacy e lo sviluppo di farmaci.<strong>\u201d<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il team di ricerca, che comprende collaboratori del Massachusetts General Hospital, Cure HHT e Diagonal Therapeutics, ha utilizzato i dati dei rimborsi real-world di Komodo per valutare l&#8217;onere economico della malattia in una coorte di oltre 24.000 pazienti nel 2022 e nel 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I risultati principali della pubblicazione includono:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In particolare, la prevalenza del trapianto di fegato tra i pazienti affetti da HHT, derivante da complicazioni di MAV epatiche, \u00e8 stata 40 volte superiore rispetto alla popolazione generale degli Stati Uniti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I costi per paziente all&#8217;anno (PPPY) per le persone che convivono con l&#8217;HHT sono paragonabili o superiori a quelli di altre malattie rare e ad alto consumo di risorse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il sanguinamento e le sue conseguenze sono stati identificati come i principali fattori trainanti dei costi sanitari.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I costi medi PPPY per tutti i pazienti HHT sono stati superiori a 19.000 $ nel 2022 e nel 2023, circa il 20% in pi\u00f9 rispetto a quelli per l&#8217;anemia falciforme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I pazienti HHT con anemia, pur rappresentando quasi il 60% della popolazione di pazienti HHT, sono stati responsabili di circa l&#8217;80% dei costi medici diretti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c<\/strong>Slipstream \u00e8 stata fondata sulla convinzione che la tecnologia debba consentire all&#8217;industria delle scienze della vita di muoversi pi\u00f9 velocemente, lavorare in modo pi\u00f9 intelligente e operare in modo pi\u00f9 efficiente<strong>\u201d<\/strong>, ha dichiarato <strong>Brandon McKay<\/strong>, Chief Executive Officer di Slipstream. <strong>\u201c<\/strong>Studi come questo confermano come i dati giusti, abbinati alla giusta competenza, possano ridefinire ci\u00f2 che \u00e8 possibile nella sanit\u00e0. Questa collaborazione \u00e8 esattamente il tipo di lavoro che ci impegniamo a fare collaborando con innovatori in tutto l&#8217;ecosistema per sbloccare il potere dei dati real-world e delle piattaforme digitali. Il nostro obiettivo \u00e8 sempre quello di accelerare l&#8217;impatto dove conta di pi\u00f9, migliorando i risultati per i pazienti.<strong>\u201d<\/strong>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo studio fondamentale fornisce prove critiche dell&#8217;alto livello di bisogni insoddisfatti per i pazienti che convivono con l&#8217;HHT, i quali hanno poche opzioni di trattamento e nessun farmaco approvato che modifichi la malattia o sia in grado di rallentarne o arrestarne la progressione. Questo studio rafforza la tesi a favore del futuro sviluppo terapeutico ed \u00e8 un esempio del valore che le evidenze real-world e il database sanitario Komodo apportano al settore delle malattie rare. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;articolo completo \u00e8 disponibile online tramite l&#8217;<em>American Journal of Hematology<\/em>: <a href=\"https:\/\/doi.org\/10.1002\/ajh.27756\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/doi.org\/10.1002\/ajh.27756<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informazioni su Slipstream<\/strong><br\/>Slipstream \u00e8 un partner tecnologico di fiducia al servizio esclusivo dell&#8217;industria delle scienze della vita. Il nostro team globale apporta una profonda competenza nel settore e soluzioni pragmatiche end-to-end che semplificano sfide complesse lungo l&#8217;intero ciclo di vita del prodotto. Operiamo con rapidit\u00e0, conformit\u00e0 e lungimiranza, consentendo ai clienti di accelerare la ricerca, ottimizzare il time-to-market e migliorare i risultati per i pazienti, garantendo che la tecnologia tenga il passo con la loro missione che cambia la vita.   <a href=\"https:\/\/www.slipstream-it.com\/\">Scopri di pi\u00f9 su Slipstream IT<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informazioni sulla pratica Digital CRO di Slipstream<\/strong><br\/>La pratica Digital CRO di Slipstream sta facendo progredire lo sviluppo di farmaci utilizzando dati real-world e la scienza dei dati attuale per creare controlli esterni\/sintetici e ibridi real-world\/placebo come base primaria per l&#8217;approvazione di farmaci sviluppati per trattare malattie rare. In qualit\u00e0 di leader di mercato nelle piattaforme digitali farmaceutiche, Slipstream combina una profonda competenza terapeutica con un&#8217;esperienza normativa reale e una tecnologia leader del settore per aiutare le aziende che si occupano di malattie rare a ottenere l&#8217;approvazione pi\u00f9 velocemente e a costi significativamente ridotti. Utilizzando ampi database nazionali, Slipstream assiste anche nell&#8217;identificazione dei siti e nel reclutamento per studi clinici sulle malattie rare.   <a href=\"https:\/\/www.slipstream-it.com\/cro\">Scopri di pi\u00f9 sulla nostra pratica Digital CRO leader di mercato<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blue Bell, PA \u2013 10 luglio 2025 \u2013 Slipstream, partner tecnologico di fiducia al servizio dell&#8217;industria farmaceutica e biofarmaceutica, \u00e8 orgogliosa di annunciare la sua co-autoria di uno studio rivoluzionario sulla teleangiectasia emorragica ereditaria (HHT), recentemente pubblicato sull&#8217;American Journal of Hematology. Lo studio, \u201cCharacterizing the Healthcare Utilization and Costs of Hereditary Hemorrhagic Telangiectasia\u201d, \u00e8 il [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3227,"template":"","resource_type":[89],"business_need":[113,117,121,125],"service_type":[13],"topic":[133],"class_list":["post-3711","resource","type-resource","status-publish","has-post-thumbnail","hentry","resource_type-article-it","business_need-emerging-biotech-it","business_need-large-pharma-it","business_need-rare-disease-innovators-it","business_need-small-mid-sized-healthcare-it","service_type-digital-cro-offerings","topic-clinical-it-solutions-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell&#039;American Journal of Hematology &#062; Slipstream LS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell&#039;American Journal of Hematology\" \/>\n<meta property=\"og:description\" content=\"Blue Bell, PA \u2013 10 luglio 2025 \u2013 Slipstream, partner tecnologico di fiducia al servizio dell&#8217;industria farmaceutica e biofarmaceutica, \u00e8 orgogliosa di annunciare la sua co-autoria di uno studio rivoluzionario sulla teleangiectasia emorragica ereditaria (HHT), recentemente pubblicato sull&#8217;American Journal of Hematology. Lo studio, \u201cCharacterizing the Healthcare Utilization and Costs of Hereditary Hemorrhagic Telangiectasia\u201d, \u00e8 il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/\" \/>\n<meta property=\"og:site_name\" content=\"Slipstream LS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-19T01:31:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/02\/hht-pr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"809\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/\",\"url\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/\",\"name\":\"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell'American Journal of Hematology &#062; Slipstream LS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.slipstreamls.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hht-pr.png\",\"datePublished\":\"2026-03-02T21:32:21+00:00\",\"dateModified\":\"2026-06-19T01:31:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.slipstreamls.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hht-pr.png\",\"contentUrl\":\"https:\\\/\\\/www.slipstreamls.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/hht-pr.png\",\"width\":809,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\",\"item\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell&#8217;American Journal of Hematology\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/\",\"name\":\"Slipstream\",\"description\":\"Life sciences, accelerated. Expertise delivered.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/#organization\",\"name\":\"Slipstream LS\",\"url\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.slipstreamls.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/slipstream-life-sciences-mark.jpg\",\"contentUrl\":\"https:\\\/\\\/www.slipstreamls.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/slipstream-life-sciences-mark.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Slipstream LS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.slipstreamls.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/slipstreamls\\\/posts\\\/?feedView=all\"],\"description\":\"Slipstream is a life sciences technology partner focused on intelligent, compliant, and trusted execution across R&D, enterprise platforms, data, and operations. We help organizations accelerate research, optimize operations, and implement technology that keeps pace with life-changing missions in an increasingly complex regulatory environment.\",\"email\":\"info@slipstreamls.com\",\"telephone\":\"+1-267-705-4000\",\"legalName\":\"Slipstream IT, LLC\",\"foundingDate\":\"2020-01-01\",\"naics\":\"5415\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"501\",\"maxValue\":\"1000\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell'American Journal of Hematology &#062; Slipstream LS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/","og_locale":"it_IT","og_type":"article","og_title":"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell'American Journal of Hematology","og_description":"Blue Bell, PA \u2013 10 luglio 2025 \u2013 Slipstream, partner tecnologico di fiducia al servizio dell&#8217;industria farmaceutica e biofarmaceutica, \u00e8 orgogliosa di annunciare la sua co-autoria di uno studio rivoluzionario sulla teleangiectasia emorragica ereditaria (HHT), recentemente pubblicato sull&#8217;American Journal of Hematology. Lo studio, \u201cCharacterizing the Healthcare Utilization and Costs of Hereditary Hemorrhagic Telangiectasia\u201d, \u00e8 il [&hellip;]","og_url":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/","og_site_name":"Slipstream LS","article_modified_time":"2026-06-19T01:31:23+00:00","og_image":[{"width":809,"height":1080,"url":"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/02\/hht-pr.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/","url":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/","name":"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell'American Journal of Hematology &#062; Slipstream LS","isPartOf":{"@id":"https:\/\/www.slipstreamls.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/#primaryimage"},"image":{"@id":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/#primaryimage"},"thumbnailUrl":"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/02\/hht-pr.png","datePublished":"2026-03-02T21:32:21+00:00","dateModified":"2026-06-19T01:31:23+00:00","breadcrumb":{"@id":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/#primaryimage","url":"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/02\/hht-pr.png","contentUrl":"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/02\/hht-pr.png","width":809,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.slipstreamls.com\/it\/resources\/slipstream-co-authors-first-comprehensive-cost-study-on-hereditary-hemorrhagic-telangiectasia-in-the-american-journal-of-hematology\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.slipstreamls.com\/it\/"},{"@type":"ListItem","position":2,"name":"Resources","item":"https:\/\/www.slipstreamls.com\/it\/resources\/"},{"@type":"ListItem","position":3,"name":"Slipstream co-autrice del primo studio completo sui costi della teleangiectasia emorragica ereditaria nell&#8217;American Journal of Hematology"}]},{"@type":"WebSite","@id":"https:\/\/www.slipstreamls.com\/it\/#website","url":"https:\/\/www.slipstreamls.com\/it\/","name":"Slipstream","description":"Life sciences, accelerated. Expertise delivered.","publisher":{"@id":"https:\/\/www.slipstreamls.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.slipstreamls.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.slipstreamls.com\/it\/#organization","name":"Slipstream LS","url":"https:\/\/www.slipstreamls.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.slipstreamls.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/03\/slipstream-life-sciences-mark.jpg","contentUrl":"https:\/\/www.slipstreamls.com\/wp-content\/uploads\/2026\/03\/slipstream-life-sciences-mark.jpg","width":1200,"height":1200,"caption":"Slipstream LS"},"image":{"@id":"https:\/\/www.slipstreamls.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/slipstreamls\/posts\/?feedView=all"],"description":"Slipstream is a life sciences technology partner focused on intelligent, compliant, and trusted execution across R&D, enterprise platforms, data, and operations. We help organizations accelerate research, optimize operations, and implement technology that keeps pace with life-changing missions in an increasingly complex regulatory environment.","email":"info@slipstreamls.com","telephone":"+1-267-705-4000","legalName":"Slipstream IT, LLC","foundingDate":"2020-01-01","naics":"5415","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"501","maxValue":"1000"}}]}},"_links":{"self":[{"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/resource\/3711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/types\/resource"}],"author":[{"embeddable":true,"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/users\/6"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/media\/3227"}],"wp:attachment":[{"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/media?parent=3711"}],"wp:term":[{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/resource_type?post=3711"},{"taxonomy":"business_need","embeddable":true,"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/business_need?post=3711"},{"taxonomy":"service_type","embeddable":true,"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/service_type?post=3711"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.slipstreamls.com\/it\/wp-json\/wp\/v2\/topic?post=3711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}